{"id":5564,"date":"2025-12-01T11:20:50","date_gmt":"2025-12-01T10:20:50","guid":{"rendered":"https:\/\/collectifgru.fr\/?p=5564"},"modified":"2025-12-09T18:16:35","modified_gmt":"2025-12-09T17:16:35","slug":"centre-de-tri-2","status":"publish","type":"post","link":"https:\/\/collectifgru.fr\/index.php\/2025\/12\/01\/centre-de-tri-2\/","title":{"rendered":"Centre de Tri"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"5564\" class=\"elementor elementor-5564\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b0f3b47 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"b0f3b47\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-0bad996 col-gauche\" data-id=\"0bad996\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36beb6e elementor-widget elementor-widget-image-gallery\" data-id=\"36beb6e\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-1' class='gallery galleryid-5564 gallery-columns-1 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a  href='https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2658-1-scaled.jpg'><img fetchpriority=\"high\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2658-1-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2658-1-scaled.jpg 2560w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2658-1-300x200.jpg 300w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2658-1-1024x683.jpg 1024w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2658-1-768x512.jpg 768w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2658-1-1536x1024.jpg 1536w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2658-1-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cb4ffb8 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"cb4ffb8\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-2' class='gallery galleryid-5564 gallery-columns-1 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a  href='https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2122-scaled.jpg'><img decoding=\"async\" width=\"1707\" height=\"2560\" src=\"https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2122-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2122-scaled.jpg 1707w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2122-200x300.jpg 200w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2122-683x1024.jpg 683w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2122-768x1152.jpg 768w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2122-1024x1536.jpg 1024w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2122-1365x2048.jpg 1365w\" sizes=\"(max-width: 1707px) 100vw, 1707px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a  href='https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2237-scaled.jpg'><img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2237-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2237-scaled.jpg 2560w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2237-300x200.jpg 300w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2237-1024x683.jpg 1024w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2237-768x512.jpg 768w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2237-1536x1024.jpg 1536w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2237-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a151d4 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"1a151d4\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-3' class='gallery galleryid-5564 gallery-columns-2 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a  href='https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_1906-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1707\" height=\"2560\" src=\"https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_1906-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_1906-scaled.jpg 1707w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_1906-200x300.jpg 200w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_1906-683x1024.jpg 683w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_1906-768x1152.jpg 768w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_1906-1024x1536.jpg 1024w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_1906-1365x2048.jpg 1365w\" sizes=\"(max-width: 1707px) 100vw, 1707px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a  href='https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_1932-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1707\" height=\"2560\" src=\"https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_1932-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_1932-scaled.jpg 1707w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_1932-200x300.jpg 200w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_1932-683x1024.jpg 683w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_1932-768x1152.jpg 768w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_1932-1024x1536.jpg 1024w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_1932-1365x2048.jpg 1365w\" sizes=\"(max-width: 1707px) 100vw, 1707px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6386186 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"6386186\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-4' class='gallery galleryid-5564 gallery-columns-1 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a  href='https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2607-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1707\" height=\"2560\" src=\"https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2607-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2607-scaled.jpg 1707w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2607-200x300.jpg 200w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2607-683x1024.jpg 683w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2607-768x1152.jpg 768w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2607-1024x1536.jpg 1024w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2607-1365x2048.jpg 1365w\" sizes=\"(max-width: 1707px) 100vw, 1707px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a  href='https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_1943-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_1943-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_1943-scaled.jpg 2560w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_1943-300x200.jpg 300w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_1943-1024x683.jpg 1024w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_1943-768x512.jpg 768w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_1943-1536x1024.jpg 1536w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_1943-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57a3405 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"57a3405\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-5' class='gallery galleryid-5564 gallery-columns-2 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a  href='https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2089-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1707\" height=\"2560\" src=\"https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2089-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2089-scaled.jpg 1707w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2089-200x300.jpg 200w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2089-683x1024.jpg 683w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2089-768x1152.jpg 768w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2089-1024x1536.jpg 1024w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2089-1365x2048.jpg 1365w\" sizes=\"(max-width: 1707px) 100vw, 1707px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a  href='https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2294-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1707\" height=\"2560\" src=\"https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2294-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2294-scaled.jpg 1707w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2294-200x300.jpg 200w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2294-683x1024.jpg 683w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2294-768x1152.jpg 768w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2294-1024x1536.jpg 1024w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2294-1365x2048.jpg 1365w\" sizes=\"(max-width: 1707px) 100vw, 1707px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c448071 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"c448071\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-6' class='gallery galleryid-5564 gallery-columns-1 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a  href='https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_1957-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_1957-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_1957-scaled.jpg 2560w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_1957-300x200.jpg 300w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_1957-1024x683.jpg 1024w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_1957-768x512.jpg 768w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_1957-1536x1024.jpg 1536w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_1957-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a  href='https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2357-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1707\" height=\"2560\" src=\"https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2357-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2357-scaled.jpg 1707w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2357-200x300.jpg 200w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2357-683x1024.jpg 683w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2357-768x1152.jpg 768w\" sizes=\"(max-width: 1707px) 100vw, 1707px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44e0fc5 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"44e0fc5\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-7' class='gallery galleryid-5564 gallery-columns-2 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a  href='https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2480-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1707\" height=\"2560\" src=\"https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2480-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2480-scaled.jpg 1707w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2480-200x300.jpg 200w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2480-683x1024.jpg 683w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2480-768x1152.jpg 768w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2480-1024x1536.jpg 1024w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2480-1365x2048.jpg 1365w\" sizes=\"(max-width: 1707px) 100vw, 1707px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a  href='https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2510-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1707\" height=\"2560\" src=\"https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2510-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2510-scaled.jpg 1707w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2510-200x300.jpg 200w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2510-683x1024.jpg 683w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2510-768x1152.jpg 768w\" sizes=\"(max-width: 1707px) 100vw, 1707px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a  href='https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2364-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1707\" height=\"2560\" src=\"https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2364-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2364-scaled.jpg 1707w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2364-200x300.jpg 200w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2364-683x1024.jpg 683w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2364-768x1152.jpg 768w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2364-1024x1536.jpg 1024w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2364-1365x2048.jpg 1365w\" sizes=\"(max-width: 1707px) 100vw, 1707px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a  href='https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2365-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1707\" height=\"2560\" src=\"https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2365-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2365-scaled.jpg 1707w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2365-200x300.jpg 200w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2365-683x1024.jpg 683w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2365-768x1152.jpg 768w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2365-1024x1536.jpg 1024w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2365-1365x2048.jpg 1365w\" sizes=\"(max-width: 1707px) 100vw, 1707px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a  href='https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2083-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1707\" height=\"2560\" src=\"https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2083-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2083-scaled.jpg 1707w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2083-200x300.jpg 200w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2083-683x1024.jpg 683w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2083-768x1152.jpg 768w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2083-1024x1536.jpg 1024w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2083-1365x2048.jpg 1365w\" sizes=\"(max-width: 1707px) 100vw, 1707px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a  href='https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2087-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1707\" height=\"2560\" src=\"https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2087-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2087-scaled.jpg 1707w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2087-200x300.jpg 200w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2087-683x1024.jpg 683w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2087-768x1152.jpg 768w\" sizes=\"(max-width: 1707px) 100vw, 1707px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ca4367 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"2ca4367\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-8' class='gallery galleryid-5564 gallery-columns-1 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a  href='https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2613-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1707\" height=\"2560\" src=\"https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2613-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2613-scaled.jpg 1707w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2613-200x300.jpg 200w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2613-683x1024.jpg 683w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2613-768x1152.jpg 768w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2613-1024x1536.jpg 1024w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2613-1365x2048.jpg 1365w\" sizes=\"(max-width: 1707px) 100vw, 1707px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-421e14e gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"421e14e\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-9' class='gallery galleryid-5564 gallery-columns-2 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a  href='https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2587-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1707\" height=\"2560\" src=\"https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2587-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2587-scaled.jpg 1707w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2587-200x300.jpg 200w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2587-683x1024.jpg 683w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2587-768x1152.jpg 768w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2587-1024x1536.jpg 1024w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2587-1365x2048.jpg 1365w\" sizes=\"(max-width: 1707px) 100vw, 1707px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a  href='https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2232-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1707\" height=\"2560\" src=\"https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2232-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2232-scaled.jpg 1707w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2232-200x300.jpg 200w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2232-683x1024.jpg 683w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2232-768x1152.jpg 768w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2232-1024x1536.jpg 1024w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2232-1365x2048.jpg 1365w\" sizes=\"(max-width: 1707px) 100vw, 1707px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-90b6818 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"90b6818\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-10' class='gallery galleryid-5564 gallery-columns-2 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a  href='https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_1908-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1707\" height=\"2560\" src=\"https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_1908-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_1908-scaled.jpg 1707w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_1908-200x300.jpg 200w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_1908-683x1024.jpg 683w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_1908-768x1152.jpg 768w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_1908-1024x1536.jpg 1024w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_1908-1365x2048.jpg 1365w\" sizes=\"(max-width: 1707px) 100vw, 1707px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a  href='https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2368-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1707\" height=\"2560\" src=\"https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2368-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2368-scaled.jpg 1707w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2368-200x300.jpg 200w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2368-683x1024.jpg 683w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2368-768x1152.jpg 768w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2368-1024x1536.jpg 1024w, https:\/\/collectifgru.fr\/wp-content\/uploads\/2025\/12\/MG_2368-1365x2048.jpg 1365w\" sizes=\"(max-width: 1707px) 100vw, 1707px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e60de0b col-droite\" data-id=\"e60de0b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77103dd elementor-widget elementor-widget-heading\" data-id=\"77103dd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Centre de tri et de r\u00e9emploi<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3af2844 elementor-widget elementor-widget-heading\" data-id=\"3af2844\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dispositif pour le tri et la valorisation des d\u00e9chets de l'ENSA Nantes<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c83cbc elementor-widget elementor-widget-spacer\" data-id=\"9c83cbc\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-640090d elementor-widget elementor-widget-text-editor\" data-id=\"640090d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">Au contact des enjeux de l\u2019architecture, le domaine de la construction occupe une place centrale dans la gestion des ressources plan\u00e9taires tout en \u00e9tant l\u2019un des plus grands producteurs de carbone et de d\u00e9chets. En France en 2024, le secteur du b\u00e2timent repr\u00e9sente 23% des \u00e9missions de GES et produit 46 millions de tonnes de d\u00e9chets annuels.<\/p><p class=\"p1\">La mise en place d\u2019un centre de tri et de r\u00e9emploi \u00e0 l\u2019ensa Nantes vise \u00e0 offrir aux \u00e9tudiants, aux enseignants et aux autres acteurs de l\u2019\u00e9cole un nouvel outil qui s\u2019int\u00e8gre directement \u00e0 la p\u00e9dagogie et \u00e0 la recherche tout en favorisant partout une prise de conscience progressive. Au-del\u00e0 de la r\u00e9duction des co\u00fbts et de la limitation des impacts environnementaux, cette approche ancre les \u00e9tudiants dans une r\u00e9alit\u00e9 concr\u00e8te o\u00f9 chaque choix a des cons\u00e9quences tangibles.<\/p><p class=\"p1\">Ce dispositif se pr\u00e9sente comme un espace ouvert et en libre-service, accessible \u00e0 tous les usagers de l\u2019\u00e9cole, et r\u00e9pond aux objectifs suivants :<\/p><p class=\"p2\"><b>Favoriser le r\u00e9emploi <\/b><\/p><p class=\"p2\">&#8211; En diffusant et favorisant les m\u00e9thodes de conception et de fabrication qui permettent le r\u00e9emploi des mat\u00e9riaux utilis\u00e9s.<br \/>&#8211; En encourageant le d\u00e9montage s\u00e9lectif des maquettes, projets et prototypes, gr\u00e2ce \u00e0 un espace d\u00e9di\u00e9 : le grand \u00e9tabli.<br \/>&#8211; En favorisant le tri dans un espace de stockage identifiable, modulable et extensible, avec des contenants unifi\u00e9s pour guider les utilisateurs.<br \/>&#8211; En donnant acc\u00e8s facilement et gratuitement aux mat\u00e9riaux tri\u00e9s par type et par taille apr\u00e8s d\u00e9montage.<br \/>&#8211; En sensibilisant les utilisateurs \u00e0 la valeur \u00e9conomique et \u00e9cologique des pratiques de recyclage.<\/p><p class=\"p2\"><b>Am\u00e9liorer la gestion des d\u00e9chets de l\u2019ensa Nantes <\/b><\/p><p class=\"p1\">&#8211; En rendant visibles et accessibles les diff\u00e9rentes bennes pour lutter contre la culture du \u00ab tout-venant \u00bb.<br \/>&#8211; En expliquant le fonctionnement des fili\u00e8res de recyclage et les conditions de valorisation des d\u00e9chets.<br \/>&#8211; En rassemblant en un lieu unique tous les mat\u00e9riaux et d\u00e9chets produits par l\u2019\u00e9tablissement.<\/p><p><i>Photographies \u00a9 \u2013\u00a0<em>Collectif Gru\u00a0<\/em><\/i><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb8dee7 elementor-widget elementor-widget-spacer\" data-id=\"bb8dee7\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0e45ed7 elementor-widget elementor-widget-text-editor\" data-id=\"0e45ed7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>[LOCALISATION]<\/strong><\/p><p>ENSA Nantes, France<\/p><p><strong><span style=\"font-size: 12px;\">\u00a0<\/span><\/strong><\/p><p><strong><span style=\"font-size: 12px;\">[ 2024]<\/span><\/strong><\/p><p><span style=\"font-size: 12px;\">livr\u00e9<\/span><\/p><p><span style=\"font-size: 12px;\">\u00a0<\/span><\/p><p><strong>[COMMANDITAIRE]<\/strong><\/p><p>\u00c9cole Nationale Sup\u00e9rieur<\/p><p>d&rsquo;Architecture de Nantes<\/p><p><strong>\u00a0<\/strong><\/p><p><strong>[CONCEPTION]<\/strong><\/p><p>Collectif Gru<\/p><p><strong>\u00a0<\/strong><\/p><p><strong>[R\u00c9ALISATION]<\/strong><\/p><p>Collectif Gru<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53dbcce elementor-widget elementor-widget-spacer\" data-id=\"53dbcce\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Centre de tri et de r\u00e9emploi Dispositif pour le tri et la valorisation des d\u00e9chets de l&rsquo;ENSA Nantes Au contact des enjeux de l\u2019architecture, le domaine de la construction occupe une place centrale dans la gestion des ressources plan\u00e9taires tout en \u00e9tant l\u2019un des plus grands producteurs de carbone et de d\u00e9chets. En France en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[5,1],"tags":[],"class_list":["post-5564","post","type-post","status-publish","format-standard","hentry","category-scenographie","category-tous-les-projets","entry"],"_links":{"self":[{"href":"https:\/\/collectifgru.fr\/index.php\/wp-json\/wp\/v2\/posts\/5564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/collectifgru.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/collectifgru.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/collectifgru.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/collectifgru.fr\/index.php\/wp-json\/wp\/v2\/comments?post=5564"}],"version-history":[{"count":38,"href":"https:\/\/collectifgru.fr\/index.php\/wp-json\/wp\/v2\/posts\/5564\/revisions"}],"predecessor-version":[{"id":6380,"href":"https:\/\/collectifgru.fr\/index.php\/wp-json\/wp\/v2\/posts\/5564\/revisions\/6380"}],"wp:attachment":[{"href":"https:\/\/collectifgru.fr\/index.php\/wp-json\/wp\/v2\/media?parent=5564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/collectifgru.fr\/index.php\/wp-json\/wp\/v2\/categories?post=5564"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/collectifgru.fr\/index.php\/wp-json\/wp\/v2\/tags?post=5564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}